{"id":21031,"date":"2023-06-30T15:30:42","date_gmt":"2023-06-30T18:30:42","guid":{"rendered":"https:\/\/www.certaja.com.br\/fiqueligado\/?p=21031"},"modified":"2023-06-30T15:30:42","modified_gmt":"2023-06-30T18:30:42","slug":"espaco-livre-73","status":"publish","type":"post","link":"https:\/\/www.certaja.com.br\/fiqueligado\/espaco-livre-73\/","title":{"rendered":"Espa\u00e7o Livre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19275\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/01\/ESPACO-LIVRE-5.png\" alt=\"\" width=\"1024\" height=\"300\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/01\/ESPACO-LIVRE-5.png 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/01\/ESPACO-LIVRE-5-300x88.png 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/01\/ESPACO-LIVRE-5-768x225.png 768w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/>No Espa\u00e7o Livre desta semana, a colaboradora <strong>Maria de F\u00e1tima Silva Hassen<\/strong> indica um pequeno texto, extra\u00eddo do blog de Daniel Azevedo. Confira:<\/p>\n<p><strong>N\u00e3o posso esperar resultados diferentes com atitudes iguais<\/strong><\/p>\n<p>Todos n\u00f3s temos aqueles desafios mais dif\u00edceis onde desejamos e colocamos a expectativa de que as coisas mudem e que tenham um resultado diferente.<br \/>\nN\u00e3o podemos ter coisas diferentes se fazemos tudo igual, ent\u00e3o, para termos algo diferente, precisamos pensar e agir de forma diferente.<\/p>\n<p>A mudan\u00e7a \u00e9 algo de normal na vida, de um minuto passa para outro, de dia passa para a noite, por isso, nada melhor do que pararmos um pouco, vermos o que h\u00e1 para corrigir e alterarmos as coisas, vivendo e aceitando as mudan\u00e7as. Se quisermos algo diferente, temos de pensar e agir de forma diferente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No Espa\u00e7o Livre desta semana, a colaboradora Maria de F\u00e1tima Silva Hassen indica um pequeno texto, extra\u00eddo do blog de Daniel Azevedo. Confira: N\u00e3o posso esperar resultados diferentes com atitudes iguais Todos n\u00f3s temos aqueles desafios mais dif\u00edceis onde desejamos e colocamos a expectativa de que as coisas mudem e que tenham um resultado diferente. &hellip; <a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/espaco-livre-73\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Espa\u00e7o Livre&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[563],"tags":[76],"class_list":["post-21031","post","type-post","status-publish","format-standard","hentry","category-edicao-814","tag-espaco-livre"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Cristiane Lautert","author_link":"https:\/\/www.certaja.com.br\/fiqueligado\/author\/cristiane\/"},"uagb_comment_info":0,"uagb_excerpt":"No Espa\u00e7o Livre desta semana, a colaboradora Maria de F\u00e1tima Silva Hassen indica um pequeno texto, extra\u00eddo do blog de Daniel Azevedo. Confira: N\u00e3o posso esperar resultados diferentes com atitudes iguais Todos n\u00f3s temos aqueles desafios mais dif\u00edceis onde desejamos e colocamos a expectativa de que as coisas mudem e que tenham um resultado diferente.&hellip;","_links":{"self":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/comments?post=21031"}],"version-history":[{"count":2,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21031\/revisions"}],"predecessor-version":[{"id":21066,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21031\/revisions\/21066"}],"wp:attachment":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/media?parent=21031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/categories?post=21031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/tags?post=21031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}