{"id":21159,"date":"2023-07-14T15:15:10","date_gmt":"2023-07-14T18:15:10","guid":{"rendered":"https:\/\/www.certaja.com.br\/fiqueligado\/?p=21159"},"modified":"2023-07-14T15:15:10","modified_gmt":"2023-07-14T18:15:10","slug":"dica-de-saude-atividade-fisica-como-dar-o-pontape-inicial","status":"publish","type":"post","link":"https:\/\/www.certaja.com.br\/fiqueligado\/dica-de-saude-atividade-fisica-como-dar-o-pontape-inicial\/","title":{"rendered":"Dica de sa\u00fade &#8211; Atividade f\u00edsica: como dar o \u201cpontap\u00e9\u201d inicial"},"content":{"rendered":"<p>Qualquer momento \u00e9 um bom momento para come\u00e7ar a adotar h\u00e1bitos de vida mais saud\u00e1veis, como manter uma alimenta\u00e7\u00e3o equilibrada e <strong>praticar exerc\u00edcios<\/strong>.<\/p>\n<p>Falta de tempo e \u00e2nimo n\u00e3o s\u00e3o mais desculpas. N\u00e3o, voc\u00ea n\u00e3o precisa passar longas horas na academia ou correr o equivalente a uma meia maratona para colher os benef\u00edcios.\u202f E quanto \u00e0 motiva\u00e7\u00e3o, n\u00e3o \u00e9 recompensa suficiente prevenir in\u00fameras doen\u00e7as cr\u00f4nicas e melhorar outros aspectos essenciais ao seu bem-estar? D\u00ea o pontap\u00e9 inicial!<\/p>\n<p><strong>Comece aos poucos<\/strong><br \/>\nFazer pequenas mudan\u00e7as aos poucos \u00e9 muito mais eficaz e aumenta as chances de desenvolver h\u00e1bitos saud\u00e1veis \u200b\u200be duradouros.\u202f Isso porque quando voc\u00ea faz mudan\u00e7as graduais, os limites s\u00e3o muito mais f\u00e1ceis de serem superados, e a manuten\u00e7\u00e3o ser\u00e1 mais longa.<\/p>\n<p><strong>Reserve um tempinho para se movimentar<\/strong><br \/>\nA Organiza\u00e7\u00e3o Mundial da Sa\u00fade\u202frecomenda gastar pelo menos 150 minutos\u202fde atividade f\u00edsica aer\u00f3bica de intensidade moderada ou 75 minutos de atividade f\u00edsica aer\u00f3bica vigorosa por semana &#8211; ou uma combina\u00e7\u00e3o equivalente.<\/p>\n<p>Que tal uma\u202fcaminhada de 30 minutos todos os dias, ou pelo menos tr\u00eas vezes na semana? Ou escolha um esporte que voc\u00ea gosta: correr, jogar futebol ou basquete, por exemplo.<\/p>\n<figure id=\"attachment_21212\" aria-describedby=\"caption-attachment-21212\" style=\"width: 1707px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457.jpg\" data-lbwps-width=\"3162\" data-lbwps-height=\"4743\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-200x300.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21212\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-scaled.jpg 1707w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-200x300.jpg 200w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-683x1024.jpg 683w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-768x1152.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-1024x1536.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-1365x2048.jpg 1365w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/pexels-jeandaniel-francoeur-4789457-1200x1800.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/a><figcaption id=\"caption-attachment-21212\" class=\"wp-caption-text\">Foto de <a href=\"https:\/\/www.pexels.com\/pt-br\/foto\/menina-de-camisa-branca-e-shorts-azuis-jogando-futebol-4789457\/\">Jean-Daniel Francoeur\/Pexels<\/a><\/figcaption><\/figure>\n<p>Tamb\u00e9m vale passeios de bicicleta ou dan\u00e7ar ao ritmo da sua m\u00fasica favorita. At\u00e9 mesmo a limpeza da casa pode ajudar neste sentido. O importante \u00e9 se movimentar!<\/p>\n<p>Reserve algum tempo do seu dia para praticar a modalidade de exerc\u00edcio que voc\u00ea mais gosta. Isso ajudar\u00e1 a aliviar a mente, desconectando-o dos problemas com algo ben\u00e9fico para a sa\u00fade.<\/p>\n<p><strong>Quinze minutos por dia j\u00e1 s\u00e3o suficientes para sair da inatividade. <\/strong>Agora, como voc\u00ea pode acessar o Fique Ligado do seu celular, reserve um tempo em sua casa para fazer os exerc\u00edcios dos v\u00eddeos abaixo, preparados pela <a href=\"https:\/\/www.unimedvtrp.com.br\/blog\/pontape-inicial\/\">Unimed VTRP<\/a>:<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-21159-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/MOVIMENTO-Treino-de-15-min-para-pernas-e-gluteos.mp4?_=1\" \/><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/MOVIMENTO-Treino-de-15-min-para-pernas-e-gluteos.mp4\">https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/MOVIMENTO-Treino-de-15-min-para-pernas-e-gluteos.mp4<\/a><\/video><\/div>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-21159-2\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/MOVIMENTO-Treino-de-15-min-focado-em-abdomen.mp4?_=2\" \/><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/MOVIMENTO-Treino-de-15-min-focado-em-abdomen.mp4\">https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/MOVIMENTO-Treino-de-15-min-focado-em-abdomen.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Qualquer momento \u00e9 um bom momento para come\u00e7ar a adotar h\u00e1bitos de vida mais saud\u00e1veis, como manter uma alimenta\u00e7\u00e3o equilibrada e praticar exerc\u00edcios. Falta de tempo e \u00e2nimo n\u00e3o s\u00e3o mais desculpas. N\u00e3o, voc\u00ea n\u00e3o precisa passar longas horas na academia ou correr o equivalente a uma meia maratona para colher os benef\u00edcios.\u202f E quanto &hellip; <a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/dica-de-saude-atividade-fisica-como-dar-o-pontape-inicial\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Dica de sa\u00fade &#8211; Atividade f\u00edsica: como dar o \u201cpontap\u00e9\u201d inicial&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[565],"tags":[13],"class_list":["post-21159","post","type-post","status-publish","format-standard","hentry","category-edicao-816","tag-aconteceu"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Cristiane Lautert","author_link":"https:\/\/www.certaja.com.br\/fiqueligado\/author\/cristiane\/"},"uagb_comment_info":0,"uagb_excerpt":"Qualquer momento \u00e9 um bom momento para come\u00e7ar a adotar h\u00e1bitos de vida mais saud\u00e1veis, como manter uma alimenta\u00e7\u00e3o equilibrada e praticar exerc\u00edcios. Falta de tempo e \u00e2nimo n\u00e3o s\u00e3o mais desculpas. N\u00e3o, voc\u00ea n\u00e3o precisa passar longas horas na academia ou correr o equivalente a uma meia maratona para colher os benef\u00edcios.\u202f E quanto&hellip;","_links":{"self":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/comments?post=21159"}],"version-history":[{"count":5,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21159\/revisions"}],"predecessor-version":[{"id":21243,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21159\/revisions\/21243"}],"wp:attachment":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/media?parent=21159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/categories?post=21159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/tags?post=21159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}