{"id":21263,"date":"2023-07-21T14:51:53","date_gmt":"2023-07-21T17:51:53","guid":{"rendered":"https:\/\/www.certaja.com.br\/fiqueligado\/?p=21263"},"modified":"2023-07-21T14:51:53","modified_gmt":"2023-07-21T17:51:53","slug":"curso-de-aproveitamento-de-alimentos","status":"publish","type":"post","link":"https:\/\/www.certaja.com.br\/fiqueligado\/curso-de-aproveitamento-de-alimentos\/","title":{"rendered":"Curso de aproveitamento de alimentos"},"content":{"rendered":"<p dir=\"auto\">Onze merendeiras das escolas municipais de Taba\u00ed e a nutricionista Luciane Godoy de Souza tiveram dias de muita troca e aprendizado. De 17 a 19 de julho, elas participaram do curso <strong>Aproveitamento integral de alimentos<\/strong>, promovido por CERTAJA Energia, Sindicato Rural de Taquari e SENAR-RS.<\/p>\n<p dir=\"auto\"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos.jpg\" data-lbwps-width=\"3456\" data-lbwps-height=\"2304\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-300x200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21264\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-scaled.jpg 2560w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-300x200.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-1024x683.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-768x512.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-1536x1024.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-2048x1365.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/07\/Curso-alimentos-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/a>A capacita\u00e7\u00e3o, realizada na Escola Municipal de Educa\u00e7\u00e3o B\u00e1sica Nelsa Braga, em Taba\u00ed, foi ministrada pelo instrutor Marco Antonio Oliveira Flores. Aproveitamento dos alimentos, higiene, conserva\u00e7\u00e3o, armazenamento e receitas diversas fizeram parte do conte\u00fado program\u00e1tico do curso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Onze merendeiras das escolas municipais de Taba\u00ed e a nutricionista Luciane Godoy de Souza tiveram dias de muita troca e aprendizado. De 17 a 19 de julho, elas participaram do curso Aproveitamento integral de alimentos, promovido por CERTAJA Energia, Sindicato Rural de Taquari e SENAR-RS. A capacita\u00e7\u00e3o, realizada na Escola Municipal de Educa\u00e7\u00e3o B\u00e1sica Nelsa &hellip; <a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/curso-de-aproveitamento-de-alimentos\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Curso de aproveitamento de alimentos&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[566],"tags":[13],"class_list":["post-21263","post","type-post","status-publish","format-standard","hentry","category-edicao-817","tag-aconteceu"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Cristiane Lautert","author_link":"https:\/\/www.certaja.com.br\/fiqueligado\/author\/cristiane\/"},"uagb_comment_info":0,"uagb_excerpt":"Onze merendeiras das escolas municipais de Taba\u00ed e a nutricionista Luciane Godoy de Souza tiveram dias de muita troca e aprendizado. De 17 a 19 de julho, elas participaram do curso Aproveitamento integral de alimentos, promovido por CERTAJA Energia, Sindicato Rural de Taquari e SENAR-RS. A capacita\u00e7\u00e3o, realizada na Escola Municipal de Educa\u00e7\u00e3o B\u00e1sica Nelsa&hellip;","_links":{"self":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/comments?post=21263"}],"version-history":[{"count":1,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21263\/revisions"}],"predecessor-version":[{"id":21265,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/21263\/revisions\/21265"}],"wp:attachment":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/media?parent=21263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/categories?post=21263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/tags?post=21263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}