{"id":23042,"date":"2023-12-01T15:07:53","date_gmt":"2023-12-01T18:07:53","guid":{"rendered":"https:\/\/www.certaja.com.br\/fiqueligado\/?p=23042"},"modified":"2023-12-01T15:08:55","modified_gmt":"2023-12-01T18:08:55","slug":"migracao-para-o-ambiente-de-contratacao-livre","status":"publish","type":"post","link":"https:\/\/www.certaja.com.br\/fiqueligado\/migracao-para-o-ambiente-de-contratacao-livre\/","title":{"rendered":"Migra\u00e7\u00e3o para o Ambiente de Contrata\u00e7\u00e3o Livre"},"content":{"rendered":"\n<p>No dia 14 de novembro, a CERTAJA Energia fechou contrato de energia no Ambiente de Contrata\u00e7\u00e3o Livre (ACL), com o cooperado <strong>Com\u00e9rcio e Transportes JE<\/strong>, de Paverama. Entre os benef\u00edcios para a empresa que optou pela migra\u00e7\u00e3o do ambiente regulado para o ACL, est\u00e3o a redu\u00e7\u00e3o significativa no custo mensal de aquisi\u00e7\u00e3o de energia el\u00e9trica, a isen\u00e7\u00e3o do pagamento das bandeiras tarif\u00e1rias e a garantia de energia por 3 ou 5 anos, o que possibilita previsibilidade or\u00e7ament\u00e1ria.<\/p>\n\n\n\n<p>Conforme o engenheiro eletricista, <strong>Elton Santos<\/strong>, a migra\u00e7\u00e3o para o mercado de energia livre tamb\u00e9m oferece ao consumidor a liberdade de escolha do fornecedor, a contrata\u00e7\u00e3o de carga sob medida, amplo poder na tomada de decis\u00f5es, al\u00e9m de estar alinhada aos princ\u00edpios da sustentabilidade.<br><\/p>\n\n\n<style>.kb-gallery-id-23042_93db92-ee .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-23042_93db92-ee .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-23042_93db92-ee alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-slider kb-gallery-id-23042_93db92-ee kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div class=\"kt-blocks-carousel-init kb-blocks-slider kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-fade=\"true\" data-slider-dots=\"true\"data-slider-type=\"slider\"  data-slider-hover-pause=\"false\" data-slider-auto=\"\" data-slider-speed=\"7000\"><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1.jpeg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"1600\" data-lbwps-height=\"1204\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1-300x226.jpeg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1-1024x771.jpeg\" width=\"840\" height=\"632\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1.jpeg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1.jpeg\" data-id=\"23112\" class=\"wp-image-23112 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1-1024x771.jpeg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1-300x226.jpeg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1-768x578.jpeg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1-1536x1156.jpeg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1-1200x903.jpeg 1200w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.17-1.jpeg 1600w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18.jpeg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"1600\" data-lbwps-height=\"1204\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18-300x226.jpeg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18-1024x771.jpeg\" width=\"840\" height=\"632\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18.jpeg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18.jpeg\" data-id=\"23113\" class=\"wp-image-23113 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18-1024x771.jpeg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18-300x226.jpeg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18-768x578.jpeg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18-1536x1156.jpeg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18-1200x903.jpeg 1200w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-14-at-12.45.18.jpeg 1600w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>No dia 14 de novembro, a CERTAJA Energia fechou contrato de energia no Ambiente de Contrata\u00e7\u00e3o Livre (ACL), com o cooperado Com\u00e9rcio e Transportes JE, de Paverama. Entre os benef\u00edcios para a empresa que optou pela migra\u00e7\u00e3o do ambiente regulado para o ACL, est\u00e3o a redu\u00e7\u00e3o significativa no custo mensal de aquisi\u00e7\u00e3o de energia el\u00e9trica, &hellip; <a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/migracao-para-o-ambiente-de-contratacao-livre\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Migra\u00e7\u00e3o para o Ambiente de Contrata\u00e7\u00e3o Livre&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[581],"tags":[13],"class_list":["post-23042","post","type-post","status-publish","format-standard","hentry","category-edicao-832","tag-aconteceu"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Cristiane Lautert","author_link":"https:\/\/www.certaja.com.br\/fiqueligado\/author\/cristiane\/"},"uagb_comment_info":0,"uagb_excerpt":"No dia 14 de novembro, a CERTAJA Energia fechou contrato de energia no Ambiente de Contrata\u00e7\u00e3o Livre (ACL), com o cooperado Com\u00e9rcio e Transportes JE, de Paverama. Entre os benef\u00edcios para a empresa que optou pela migra\u00e7\u00e3o do ambiente regulado para o ACL, est\u00e3o a redu\u00e7\u00e3o significativa no custo mensal de aquisi\u00e7\u00e3o de energia el\u00e9trica,&hellip;","_links":{"self":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/23042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/comments?post=23042"}],"version-history":[{"count":14,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/23042\/revisions"}],"predecessor-version":[{"id":23359,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/23042\/revisions\/23359"}],"wp:attachment":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/media?parent=23042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/categories?post=23042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/tags?post=23042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}