{"id":26564,"date":"2024-09-27T14:52:00","date_gmt":"2024-09-27T17:52:00","guid":{"rendered":"https:\/\/www.certaja.com.br\/fiqueligado\/?p=26564"},"modified":"2024-09-27T14:52:05","modified_gmt":"2024-09-27T17:52:05","slug":"aniversariantes-de-outubro","status":"publish","type":"post","link":"https:\/\/www.certaja.com.br\/fiqueligado\/aniversariantes-de-outubro\/","title":{"rendered":"Aniversariantes de outubro"},"content":{"rendered":"\n<p>Outubro est\u00e1 chegando, e a lista dos colegas que far\u00e3o anivers\u00e1rio no m\u00eas j\u00e1 est\u00e1 dispon\u00edvel! Parab\u00e9ns, pessoal! Que seja um novo ciclo cheio de realiza\u00e7\u00f5es, conquistas e sa\u00fade!<br><\/p>\n\n\n\n<div class=\"wp-block-uagb-image aligncenter uagb-block-c8ef8910 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/09\/Aniversariantes-724x1024.png ,https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/09\/Aniversariantes.png 780w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/09\/Aniversariantes.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/09\/Aniversariantes-724x1024.png\" alt=\"\" class=\"uag-image-26565\" width=\"541\" height=\"765\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Outubro est\u00e1 chegando, e a lista dos colegas que far\u00e3o anivers\u00e1rio no m\u00eas j\u00e1 est\u00e1 dispon\u00edvel! Parab\u00e9ns, pessoal! Que seja um novo ciclo cheio de realiza\u00e7\u00f5es, conquistas e sa\u00fade!<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[614],"tags":[87],"class_list":["post-26564","post","type-post","status-publish","format-standard","hentry","category-edicao-864","tag-aniversarios"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Cristiane Lautert","author_link":"https:\/\/www.certaja.com.br\/fiqueligado\/author\/cristiane\/"},"uagb_comment_info":0,"uagb_excerpt":"Outubro est\u00e1 chegando, e a lista dos colegas que far\u00e3o anivers\u00e1rio no m\u00eas j\u00e1 est\u00e1 dispon\u00edvel! Parab\u00e9ns, pessoal! Que seja um novo ciclo cheio de realiza\u00e7\u00f5es, conquistas e sa\u00fade!","_links":{"self":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/26564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/comments?post=26564"}],"version-history":[{"count":3,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/26564\/revisions"}],"predecessor-version":[{"id":26693,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/26564\/revisions\/26693"}],"wp:attachment":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/media?parent=26564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/categories?post=26564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/tags?post=26564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}