{"id":27010,"date":"2024-10-25T14:01:31","date_gmt":"2024-10-25T17:01:31","guid":{"rendered":"https:\/\/www.certaja.com.br\/fiqueligado\/?p=27010"},"modified":"2024-10-25T14:04:04","modified_gmt":"2024-10-25T17:04:04","slug":"certaja-energia-inaugura-novo-posto-de-atendimento-em-vale-verde","status":"publish","type":"post","link":"https:\/\/www.certaja.com.br\/fiqueligado\/certaja-energia-inaugura-novo-posto-de-atendimento-em-vale-verde\/","title":{"rendered":"CERTAJA Energia inaugura novo posto de atendimento em Vale Verde"},"content":{"rendered":"\n<div class=\"wp-block-uagb-image uagb-block-d3bd877a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3350-1024x768.jpg ,https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3350-scaled.jpg 780w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3350-scaled.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3350-1024x768.jpg\" alt=\"\" class=\"uag-image-27014\" width=\"4032\" height=\"3024\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n\n\n\n<p><br>O novo posto de atendimento da CERTAJA Energia, em Vale Verde, entrou em funcionamento no dia 21 de outubro. A cerim\u00f4nia integrou as comemora\u00e7\u00f5es pela passagem dos 55 anos da Cooperativa, celebrados no dia 17, e inaugurou o espa\u00e7o, que conta com 40 metros quadrados, situado na Avenida Assis Brasil, ao lado da C\u00e2mara de Vereadores.<\/p>\n\n\n\n<p>\u201dEstamos investindo forte na rela\u00e7\u00e3o com o nosso cooperado, procurando levar a ele as melhores condi\u00e7\u00f5es, tanto no que diz respeito \u00e0 energia quanto ao relacionamento. Estamos colocando \u00e0 disposi\u00e7\u00e3o da regi\u00e3o e, principalmente, do munic\u00edpio de Vale Verde, este posto de atendimento que facilitar\u00e1 todo esse trabalho\u201d, destacou o presidente da Cooperativa, <strong>Renato Pereira Martins<\/strong>.<br><\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-07dc312c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3338-1024x768.jpg ,https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3338-scaled.jpg 780w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3338-scaled.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3338-1024x768.jpg\" alt=\"\" class=\"uag-image-27015\" width=\"4032\" height=\"3024\" title=\"\" loading=\"lazy\"\/><\/figure><\/div>\n\n\n\n<p><br><strong>Ederson Madruga<\/strong>, vice-presidente, ressaltou o fortalecimento da presen\u00e7a da Cooperativa com a instala\u00e7\u00e3o de novos postos de atendimento pr\u00f3prios nos munic\u00edpios de sua \u00e1rea de atua\u00e7\u00e3o. &#8220;Nosso objetivo \u00e9 nos aproximarmos do nosso cooperado, cada vez mais. Esperamos que voc\u00eas gostem e usem bastante. \u00c9 a casa de voc\u00eas tamb\u00e9m&#8221;, observou.<\/p>\n\n\n\n<p>Na nova unidade, os cooperados ter\u00e3o \u00e0 disposi\u00e7\u00e3o todos os servi\u00e7os regulamentados, exatamente como os que podem ser acessados na sede da Cooperativa, em Taquari. A opera\u00e7\u00e3o contar\u00e1 com uma colaboradora, e o atendimento ser\u00e1 realizado na segunda, quarta, quinta e sexta-feira, das 13h \u00e0s 18h.<\/p>\n\n\n\n<p>Prefeito de Vale verde, <strong>Carlos Gustavo Schuch<\/strong> destacou a import\u00e2ncia dos investimentos da CERTAJA Energia &#8211; como a obra da Subesta\u00e7\u00e3o Vale Verde &#8211; para o crescimento do munic\u00edpio e para coloc\u00e1-lo como &#8220;vitrine&#8221; para novos empreendimentos. &#8220;Vale Verde deve muito \u00e0 Cooperativa. Talvez, se n\u00e3o fosse por ela, n\u00e3o estar\u00edamos munic\u00edpio hoje, no patamar que n\u00f3s estamos&#8221;, comentou. &#8220;Com certeza, quem ganha com isso somos n\u00f3s, da comunidade&#8221;, acrescentou.<br> <\/p>\n\n\n<style>.kb-gallery-id-27010_420509-b9 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-27010_420509-b9 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-27010_420509-b9 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-slider kb-gallery-id-27010_420509-b9 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div class=\"kt-blocks-carousel-init kb-blocks-slider kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-fade=\"true\" data-slider-dots=\"true\"data-slider-type=\"slider\"  data-slider-hover-pause=\"false\" data-slider-auto=\"\" data-slider-speed=\"7000\"><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-scaled.jpg\" data-id=\"27021\" class=\"wp-image-27021 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3341-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-scaled.jpg\" data-id=\"27022\" class=\"wp-image-27022 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3354-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-scaled.jpg\" data-id=\"27020\" class=\"wp-image-27020 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3331-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-scaled.jpg\" data-id=\"27024\" class=\"wp-image-27024 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3359-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-scaled.jpg\" data-id=\"27023\" class=\"wp-image-27023 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3356-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-scaled.jpg\" data-id=\"27019\" class=\"wp-image-27019 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3314-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-scaled.jpg\" data-id=\"27025\" class=\"wp-image-27025 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3360-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-scaled.jpg\" data-id=\"27016\" class=\"wp-image-27016 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3307-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-scaled.jpg\" data-id=\"27017\" class=\"wp-image-27017 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3310-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-scaled.jpg\" data-id=\"27018\" class=\"wp-image-27018 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3311-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-scaled.jpg\" data-id=\"27026\" class=\"wp-image-27026 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3362-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\" \"><a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363.jpg\" class=\"kb-gallery-item-link\"   data-lbwps-width=\"4032\" data-lbwps-height=\"3024\" data-lbwps-srcsmall=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-300x225.jpg\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-scaled.jpg\" data-light-image=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-scaled.jpg\" data-id=\"27027\" class=\"wp-image-27027 skip-lazy\" srcset=\"https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-1024x768.jpg 1024w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-300x225.jpg 300w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-768x576.jpg 768w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-1536x1152.jpg 1536w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-2048x1536.jpg 2048w, https:\/\/www.certaja.com.br\/fiqueligado\/wp-content\/uploads\/2024\/10\/IMG_3363-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/div><\/div><\/a><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O novo posto de atendimento da CERTAJA Energia, em Vale Verde, entrou em funcionamento no dia 21 de outubro. A cerim\u00f4nia integrou as comemora\u00e7\u00f5es pela passagem dos 55 anos da Cooperativa, celebrados no dia 17, e inaugurou o espa\u00e7o, que conta com 40 metros quadrados, situado na Avenida Assis Brasil, ao lado da C\u00e2mara de &hellip; <a href=\"https:\/\/www.certaja.com.br\/fiqueligado\/certaja-energia-inaugura-novo-posto-de-atendimento-em-vale-verde\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;CERTAJA Energia inaugura novo posto de atendimento em Vale Verde&#8221;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[618],"tags":[13],"class_list":["post-27010","post","type-post","status-publish","format-standard","hentry","category-edicao-867","tag-aconteceu"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Cristiane Lautert","author_link":"https:\/\/www.certaja.com.br\/fiqueligado\/author\/cristiane\/"},"uagb_comment_info":2,"uagb_excerpt":"O novo posto de atendimento da CERTAJA Energia, em Vale Verde, entrou em funcionamento no dia 21 de outubro. A cerim\u00f4nia integrou as comemora\u00e7\u00f5es pela passagem dos 55 anos da Cooperativa, celebrados no dia 17, e inaugurou o espa\u00e7o, que conta com 40 metros quadrados, situado na Avenida Assis Brasil, ao lado da C\u00e2mara de&hellip;","_links":{"self":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/27010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/comments?post=27010"}],"version-history":[{"count":7,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/27010\/revisions"}],"predecessor-version":[{"id":27268,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/posts\/27010\/revisions\/27268"}],"wp:attachment":[{"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/media?parent=27010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/categories?post=27010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.certaja.com.br\/fiqueligado\/wp-json\/wp\/v2\/tags?post=27010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}